{"id":20302,"date":"2020-07-15T06:51:37","date_gmt":"2020-07-15T06:51:37","guid":{"rendered":"https:\/\/duoveo.com\/non-classifiee\/five-proven-healthy-lifestyle-hacks-to-lose-weight-after-50\/"},"modified":"2025-05-21T15:55:53","modified_gmt":"2025-05-21T15:55:53","slug":"cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans","status":"publish","type":"post","link":"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/","title":{"rendered":"Cinq astuces pour un mode de vie sain et perdre du poids apr\u00e8s 50 ans"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vous les avez \u00e9vit\u00e9s \u00e0 la quarantaine, mais vous craignez qu&rsquo;ils arrivent et que vous ne puissiez y \u00e9chapper.<\/p>\n<p>Les grosses fesses et le ventre.<\/p>\n<p>Vous vous regardez dans le miroir et vous \u00eates g\u00ean\u00e9. C&rsquo;est comme une lente d\u00e9composition. Votre balance ne vous aime pas. Vous n&rsquo;aimez pas ce que vous voyez.<\/p>\n<p>Vous vous sentez d\u00e9sesp\u00e9r\u00e9. Comment en \u00eates-vous arriv\u00e9 l\u00e0\u00a0?<\/p>\n<p>\u00cates-vous condamn\u00e9 \u00e0 manger du brocoli et du chou fris\u00e9 toute votre vie\u00a0? Qui peut faire \u00e7a de toute fa\u00e7on\u00a0?<\/p>\n<p>Ne vous pr\u00e9cipitez pas au march\u00e9.<\/p>\n<p>Il existe des habitudes saines et simples pour perdre du poids apr\u00e8s 50\u00a0ans, beaucoup moins contraignantes et beaucoup plus faciles \u00e0 mettre en \u0153uvre.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"626e\">Astuce pour un mode de vie sain 1 : Arr\u00eatez net les collations<\/h2>\n\n<p class=\"wp-block-paragraph\">Un beignet sucr\u00e9.<\/p>\n<p>Un petit paquet de chips.<\/p>\n<p>Une soi-disant \u00ab\u00a0barre \u00e9nerg\u00e9tique\u00a0\u00bb.<\/p>\n<p>Deux cr\u00eapes au sirop.<\/p>\n<p>Tous ces aliments contiennent \u00e0 peu pr\u00e8s le m\u00eame nombre de calories, environ 150.<br \/>Devinez lequel est le plus sain\u00a0?<\/p>\n<p>Si vous avez r\u00e9pondu \u00ab\u00a0barre \u00e9nerg\u00e9tique\u00a0\u00bb, vous avez succomb\u00e9 \u00e0 la propagande marketing \u2013 et vous avez tort.<\/p>\n<p>Non, ce sont les cr\u00eapes.<\/p>\n<p>Les cr\u00eapes sont bien plus saines car elles constituent un repas, un petit-d\u00e9jeuner.<\/p>\n<p>Ce n&rsquo;est pas le cas pour tous les autres aliments. Ce sont des en-cas.<\/p>\n<p>Les en-cas sont des aliments parasites qui peuvent s&rsquo;immiscer dans votre journ\u00e9e, dans votre routine sans que vous vous en rendiez compte. On les oublie parfois, mais ils s&rsquo;accumulent.<\/p>\n<p>Perdre du poids ne signifie pas renoncer aux aliments savoureux. Cependant, le moment et la raison de vos repas sont importants, alors mieux vaut laisser tomber les en-cas. Ils font grossir.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"4521\">Astuce pour un mode de vie sain 2 &#8211; Br\u00fblez b\u00e9b\u00e9, br\u00fblez !<\/h2>\n\n<p class=\"wp-block-paragraph\">L&rsquo;exercice br\u00fble les graisses. Cependant, certains vous diront qu&rsquo;il br\u00fble trop peu de calories pour \u00eatre efficace.<\/p>\n<p>C&rsquo;est en partie vrai, sauf si vous \u00eates en surpoids.<\/p>\n<p>Marcher trois kilom\u00e8tres br\u00fble environ 200 calories pour une personne de 82 kg et 50 pour une personne de 54 kg. Voyez-vous la tendance\u00a0?<\/p>\n<p>Avoir des kilos en trop a un c\u00f4t\u00e9 positif\u00a0: on br\u00fble plus de calories.<\/p>\n<p>La quantit\u00e9 d&rsquo;exercice est \u00e9galement importante, et la plupart des gens se trompent.<\/p>\n<p>Si vous \u00eates comme eux, vous concentrez votre temps d&rsquo;exercice en une seule s\u00e9ance \u00e0 la salle de sport, et la semaine est termin\u00e9e. C&rsquo;est \u00e9puisant et difficile \u00e0 r\u00e9cup\u00e9rer.<\/p>\n<p>Et si vous sautez votre s\u00e9ance hebdomadaire, pour une raison sans doute valable, vous divisez simplement votre dose d&rsquo;exercice moyenne par deux.<\/p>\n<p>Il existe une bien meilleure solution\u00a0: faire de l&rsquo;exercice quotidiennement.<\/p>\n<p>Vous n&rsquo;avez pas besoin de vous fixer des objectifs tr\u00e8s ambitieux (en fait, vous ne devriez pas). Il suffit d&rsquo;int\u00e9grer l&rsquo;exercice \u00e0 votre routine, matin, midi ou soir, selon votre style de vie.<\/p>\n<p>Voyez-vous, m\u00eame 20 minutes par jour repr\u00e9sentent 2 heures au total sur six jours, soit plus que la plupart des s\u00e9ances de gym, sans oublier le repos du dimanche. Ajoutez 5 minutes par jour et vous obtenez 2 heures 30 par semaine. C&rsquo;est l&rsquo;effet cumulatif magique d&rsquo;une habitude.<\/p>\n<p>Pour maintenir cette habitude saine, l&rsquo;application <a href=\"https:\/\/duoveo.com\/fr\/duoveo-lapplication-mobile\/\" target=\"_blank\" rel=\"noopener\">duoveo<\/a> vous permet de suivre et de surveiller votre activit\u00e9 tout en en faisant une exp\u00e9rience sociale agr\u00e9able.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"5e37\">Astuce n\u00b0 3 pour un mode de vie sain : faites-leur dormir<\/h2>\n\n<p class=\"wp-block-paragraph\">Saviez-vous qu&rsquo;il existe un moyen encore plus naturel de br\u00fbler des calories\u00a0?<\/p>\n<p>Il suffit de dormir.<\/p>\n\n<figure><img decoding=\"async\" src=\"https:\/\/miro.medium.com\/max\/5892\/1*L7pJ_UN9Yan2SJUvXPsD9Q.jpeg\" alt=\"Sleep is an important healthy habit to lose weight\" \/>\n<figcaption>Le sommeil br\u00fble des calories et la faim<\/figcaption>\n<\/figure>\n\n<p class=\"wp-block-paragraph\">Dormir permet de br\u00fbler environ 50 calories par heure si vous pesez 68 kg et 60 si vous pesez 84 kg. L\u00e0 encore, votre surpoids est un atout.<\/p>\n<p>Mais le sommeil ne br\u00fble pas seulement les graisses, il apaise aussi la faim.<\/p>\n<p>Selon l<a href=\"https:\/\/www.pnas.org\/doi\/abs\/10.1073\/pnas.1216951110\" target=\"_blank\" rel=\"noopener\">&lsquo;Acad\u00e9mie nationale des sciences,<\/a> le manque de sommeil cr\u00e9e une cascade de r\u00e9actions hormonales qui g\u00e9n\u00e8rent la faim et vous incitent \u00e0 manger davantage, ce qui entra\u00eene une prise de poids.<\/p>\n<p>Alors, allez vous coucher et profitez d&rsquo;une bonne nuit de sommeil.<\/p>\n<p>Quoi de plus confortable\u00a0?<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"9985\">Astuce n\u00b0 4 pour un mode de vie sain : ce que vous mangez n&rsquo;a pas d&rsquo;importance<\/h2>\n\n<p class=\"wp-block-paragraph\">\u00ab Manger moins, faire plus d&rsquo;exercice \u00bb. C&rsquo;\u00e9tait autrefois la devise d&rsquo;une vie saine.<\/p>\n\n<h3 class=\"wp-block-heading\">Manger moins n&rsquo;est pas faire un r\u00e9gime<\/h3>\n\n<p class=\"wp-block-paragraph\">Aujourd&rsquo;hui, certains experts critiquent cette approche, affirmant qu&rsquo;elle a \u00e9chou\u00e9, car suivre un r\u00e9gime est difficile et a tendance \u00e0 provoquer un effet yoyo. Vous avez peut-\u00eatre essay\u00e9 de suivre un r\u00e9gime vous-m\u00eame, sans succ\u00e8s.<\/p>\n<p>L&rsquo;important est de ne pas se limiter \u00e0 un r\u00e9gime. Il ne s&rsquo;agit pas de compter les calories. Il ne s&rsquo;agit pas de se concentrer sur un aliment en particulier, ni de se gaver de boissons prot\u00e9in\u00e9es fades. Ni de manger uniquement du chou.<\/p>\n<p>Cela signifie simplement\u00a0: manger moins.<\/p>\n<p>Un ami, obs\u00e9d\u00e9 par l&rsquo;alimentation saine et le bio, m&rsquo;a demand\u00e9 un jour comment je faisais pour rester en forme \u00e0 mon \u00e2ge et ce que je mangeais. Ma r\u00e9ponse a \u00e9t\u00e9 simple\u00a0: \u00ab\u00a0L&rsquo;important n&rsquo;est pas ce que l&rsquo;on mange, mais ce que l&rsquo;on ne mange pas.\u00a0\u00bb<\/p>\n<p><strong>\u00ab\u00a0L&rsquo;important n&rsquo;est pas ce que l&rsquo;on mange, mais ce que l&rsquo;on ne mange pas.\u00a0\u00bb<\/strong><\/p>\n<ul>\n<li>\n<p>Il existe de nombreuses fa\u00e7ons de manger moins.<\/p>\n<p>Il existe de nombreuses fa\u00e7ons de manger moins, sans n\u00e9cessiter une volont\u00e9 exceptionnelle ni l&rsquo;autoflagellation.<\/p>\n<p>Nous en avons d\u00e9j\u00e0 vu une\u00a0: bannir les grignotages.<\/p>\n<p>Le je\u00fbne intermittent est une autre m\u00e9thode simple.<\/p>\n<p>C&rsquo;est une m\u00e9thode simple pour r\u00e9duire son apport calorique\u00a0: il suffit de ne pas manger. Pas pendant longtemps \u2013 10 ou 20\u00a0heures. Vous pouvez commencer par sauter un repas, et ce, une fois par semaine maximum.<\/p>\n<p>D&rsquo;autres strat\u00e9gies concernent la fa\u00e7on dont vous mangez.<\/p>\n<p>L\u00e0 encore, il ne s&rsquo;agit pas de compter les calories ou d&rsquo;interdire des aliments, mais plut\u00f4t de comportement et d&rsquo;habitudes.<\/p>\n<\/li>\n<\/ul>\n<ul>\n<li>Servez des portions plus petites. En g\u00e9n\u00e9ral, vous mangez ce qu&rsquo;il y a dans votre assiette ; moins vous en mettez, moins vous mangez.<\/li>\n<li>Manger vari\u00e9 est une astuce utilis\u00e9e dans les bo\u00eetes \u00e0 bento japonaises : plusieurs aliments diff\u00e9rents donnent une impression d&rsquo;abondance, m\u00eame en petite quantit\u00e9.<\/li>\n<li>Ne resservez pas. Cela demande un peu d&rsquo;entra\u00eenement et de discipline. Vous ne devriez pas resservir votre assiette. Jamais.<\/li>\n<li>La \u00ab\u00a0m\u00e9thode Montignac\u00a0\u00bb est une alternative int\u00e9ressante aux r\u00e9gimes\u00a0: pas de comptage des calories, mais plut\u00f4t une concentration sur le type d&rsquo;aliment.<\/li>\n<\/ul>\n<!-- \/wp:post-content --><!-- wp:heading -->\n<h2 id=\"85c4\">Astuce n\u00b0 5 pour un mode de vie sain : manger plus ou moins<\/h2>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Apprendre \u00e0 manger moins peut \u00eatre difficile, et vous pourriez \u00eatre r\u00e9ticent et inquiet d&rsquo;y parvenir.<\/p>\n<p>Heureusement pour vous, il existe une autre astuce.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p><strong>Mangez des aliments contenant moins de calories.<\/strong><\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Facile, non\u00a0?<\/p>\n<p>Mais qu&rsquo;est-ce qu&rsquo;un aliment peu calorique\u00a0? Comment l&rsquo;identifier\u00a0?<\/p>\n<p>En bref, ce sont des aliments riches en eau, en fibres et en air. Cela inclut les fruits et l\u00e9gumes frais, et bien s\u00fbr, le brocoli et le chou fris\u00e9. Mais aussi les oranges, les litchis, les abricots, les avocats, la laitue, le chou rouge, les poivrons, les tomates, les amandes, les noix. Et le popcorn souffl\u00e9 \u00e0 l&rsquo;air libre, sans beurre ni sucre.<\/p>\n<!-- \/wp:paragraph --><!-- wp:image -->\n<figure><img decoding=\"async\" src=\"https:\/\/miro.medium.com\/max\/5753\/1*d_W4Ru-oDdrU9j5lWfiaXQ.jpeg\" alt=\"Healthy foods can be yummy  too - for instance air-popped pop corn is low calories \" \/>\n<figcaption>Une tasse de popcorn souffl\u00e9 \u00e0 l&rsquo;air ne contient que 31 calories<\/figcaption>\n<\/figure>\n<!-- \/wp:image --><!-- wp:paragraph -->\n<p>L&rsquo;id\u00e9e est de remplacer certains aliments riches en calories par ceux-ci.<\/p>\n<p>Par exemple, ces deux cr\u00eapes\u00a0: faites-en une seule et remplacez la seconde par une orange. Vous venez d&rsquo;\u00e9conomiser 20 calories.<\/p>\n<p>Ce changement est minime, mais cela repr\u00e9sente deux grammes de graisse corporelle. Multipliez cela par 30 matins et vous \u00e9conomisez 60 grammes, soit 0,13\u00a0livre par mois.<\/p>\n<p>En effectuant cette substitution au cours de la journ\u00e9e, vous pouvez facilement \u00e9conomiser 0,25 \u00e0 500\u00a0grammes de graisse par mois, que vous ne prendrez pas ou que vous perdrez.<\/p>\n<p><strong>La graisse n&rsquo;est pas le destin<\/strong><\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Pass\u00e9 la cinquantaine, vous craignez que votre forme physique ne soit termin\u00e9e.<\/p>\n<p>Vous voyez les kilos en trop s&rsquo;accumuler et vous d\u00e9sesp\u00e9rez.<\/p>\n<p>Mais les fesses rebondies et la graisse abdominale ne sont pas une fatalit\u00e9.<\/p>\n<p>Nous avons vu cinq habitudes saines qui peuvent vous aider. Elles sont simples \u00e0 mettre en place, sans changer radicalement votre alimentation et votre mode de vie.<\/p>\n<p>Mais il faut essayer.<\/p>\n<p>Il suffit d&rsquo;avoir la volont\u00e9 d&rsquo;exp\u00e9rimenter et de pers\u00e9v\u00e9rer pour attendre les r\u00e9sultats.<\/p>\n<p>L&rsquo;adaptation peut prendre des semaines, voire des mois, mais vous d\u00e9couvrirez qu&rsquo;avec un peu de pratique, certaines de ces astuces sont agr\u00e9ables. Vous les appliquerez bient\u00f4t sans r\u00e9fl\u00e9chir et, pourquoi pas, trouver vos propres astuces.<\/p>\n<p>Vous ne vous soucierez plus de votre silhouette de 50 ans, vous serez plus en forme que jamais, ou du moins pas plus mal qu&rsquo;avant.<\/p>\n<p>Il suffit de faire le premier pas. Commencez d\u00e8s maintenant\u00a0!<\/p>\n<!-- \/wp:paragraph -->","protected":false},"excerpt":{"rendered":"<p>Vous les avez \u00e9vit\u00e9s \u00e0 la quarantaine, mais vous craignez qu&rsquo;ils arrivent et que vous ne puissiez y \u00e9chapper. Les grosses fesses et le ventre. Vous vous regardez dans le miroir et vous \u00eates g\u00ean\u00e9. C&rsquo;est comme une lente d\u00e9composition. Votre balance ne vous aime pas. Vous n&rsquo;aimez pas ce que vous voyez. Vous vous [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13177,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[164],"tags":[445],"class_list":["post-20302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossier-special","tag-256-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cinq astuces pour un mode de vie sain et perdre du poids apr\u00e8s 50 ans - duoveo<\/title>\n<meta name=\"description\" content=\"Voici cinq habitudes pour une mode de vie sain que vous devriez envisager apr\u00e8s 50 ans. La forme physique n\u2019est pas si compliqu\u00e9e et la graisse n\u2019est pas le destin !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinq astuces pour un mode de vie sain et perdre du poids apr\u00e8s 50 ans - duoveo\" \/>\n<meta property=\"og:description\" content=\"Voici cinq habitudes pour une mode de vie sain que vous devriez envisager apr\u00e8s 50 ans. La forme physique n\u2019est pas si compliqu\u00e9e et la graisse n\u2019est pas le destin !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/\" \/>\n<meta property=\"og:site_name\" content=\"duoveo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/duoveo\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-15T06:51:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T15:55:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/duoveo.com\/wp-content\/uploads\/2020\/07\/1_K9BJOVXej6joCFAVSOVt4g.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"loic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"loic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/bien-etre-physique\\\/dossier-special\\\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/bien-etre-physique\\\/dossier-special\\\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\\\/\"},\"author\":{\"name\":\"loic\",\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/#\\\/schema\\\/person\\\/eb034ebdf6a49f948eeab02c6b1cce7f\"},\"headline\":\"Cinq astuces pour un mode de vie sain et perdre du poids apr\u00e8s 50 ans\",\"datePublished\":\"2020-07-15T06:51:37+00:00\",\"dateModified\":\"2025-05-21T15:55:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/bien-etre-physique\\\/dossier-special\\\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\\\/\"},\"wordCount\":1535,\"publisher\":{\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/bien-etre-physique\\\/dossier-special\\\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/duoveo.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/1_K9BJOVXej6joCFAVSOVt4g.jpeg\",\"keywords\":[\"256\"],\"articleSection\":[\"dossier sp\u00e9cial\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/bien-etre-physique\\\/dossier-special\\\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\\\/\",\"url\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/bien-etre-physique\\\/dossier-special\\\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\\\/\",\"name\":\"Cinq astuces pour un mode de vie sain et perdre du poids apr\u00e8s 50 ans - duoveo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/bien-etre-physique\\\/dossier-special\\\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/bien-etre-physique\\\/dossier-special\\\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/duoveo.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/1_K9BJOVXej6joCFAVSOVt4g.jpeg\",\"datePublished\":\"2020-07-15T06:51:37+00:00\",\"dateModified\":\"2025-05-21T15:55:53+00:00\",\"description\":\"Voici cinq habitudes pour une mode de vie sain que vous devriez envisager apr\u00e8s 50 ans. La forme physique n\u2019est pas si compliqu\u00e9e et la graisse n\u2019est pas le destin !\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/duoveo.com\\\/fr\\\/bien-etre-physique\\\/dossier-special\\\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/bien-etre-physique\\\/dossier-special\\\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/duoveo.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/1_K9BJOVXej6joCFAVSOVt4g.jpeg\",\"contentUrl\":\"https:\\\/\\\/duoveo.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/1_K9BJOVXej6joCFAVSOVt4g.jpeg\",\"width\":700,\"height\":466,\"caption\":\"mode de vie sain\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/\",\"name\":\"duoveo\",\"description\":\"Your story, beautifully told - Created with WordPress managed by IONOS\",\"publisher\":{\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/#organization\",\"name\":\"duoveo\",\"url\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/duoveo.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DuoVeo_logo-black_256.png\",\"contentUrl\":\"https:\\\/\\\/duoveo.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/DuoVeo_logo-black_256.png\",\"width\":256,\"height\":256,\"caption\":\"duoveo\"},\"image\":{\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/duoveo\",\"https:\\\/\\\/www.instagram.com\\\/duo.veo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/duoveo.com\\\/fr\\\/#\\\/schema\\\/person\\\/eb034ebdf6a49f948eeab02c6b1cce7f\",\"name\":\"loic\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cinq astuces pour un mode de vie sain et perdre du poids apr\u00e8s 50 ans - duoveo","description":"Voici cinq habitudes pour une mode de vie sain que vous devriez envisager apr\u00e8s 50 ans. La forme physique n\u2019est pas si compliqu\u00e9e et la graisse n\u2019est pas le destin !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/","og_locale":"fr_FR","og_type":"article","og_title":"Cinq astuces pour un mode de vie sain et perdre du poids apr\u00e8s 50 ans - duoveo","og_description":"Voici cinq habitudes pour une mode de vie sain que vous devriez envisager apr\u00e8s 50 ans. La forme physique n\u2019est pas si compliqu\u00e9e et la graisse n\u2019est pas le destin !","og_url":"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/","og_site_name":"duoveo","article_publisher":"https:\/\/facebook.com\/duoveo","article_published_time":"2020-07-15T06:51:37+00:00","article_modified_time":"2025-05-21T15:55:53+00:00","og_image":[{"width":700,"height":466,"url":"https:\/\/duoveo.com\/wp-content\/uploads\/2020\/07\/1_K9BJOVXej6joCFAVSOVt4g.jpeg","type":"image\/jpeg"}],"author":"loic","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"loic","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/#article","isPartOf":{"@id":"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/"},"author":{"name":"loic","@id":"https:\/\/duoveo.com\/fr\/#\/schema\/person\/eb034ebdf6a49f948eeab02c6b1cce7f"},"headline":"Cinq astuces pour un mode de vie sain et perdre du poids apr\u00e8s 50 ans","datePublished":"2020-07-15T06:51:37+00:00","dateModified":"2025-05-21T15:55:53+00:00","mainEntityOfPage":{"@id":"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/"},"wordCount":1535,"publisher":{"@id":"https:\/\/duoveo.com\/fr\/#organization"},"image":{"@id":"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/#primaryimage"},"thumbnailUrl":"https:\/\/duoveo.com\/wp-content\/uploads\/2020\/07\/1_K9BJOVXej6joCFAVSOVt4g.jpeg","keywords":["256"],"articleSection":["dossier sp\u00e9cial"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/","url":"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/","name":"Cinq astuces pour un mode de vie sain et perdre du poids apr\u00e8s 50 ans - duoveo","isPartOf":{"@id":"https:\/\/duoveo.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/#primaryimage"},"image":{"@id":"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/#primaryimage"},"thumbnailUrl":"https:\/\/duoveo.com\/wp-content\/uploads\/2020\/07\/1_K9BJOVXej6joCFAVSOVt4g.jpeg","datePublished":"2020-07-15T06:51:37+00:00","dateModified":"2025-05-21T15:55:53+00:00","description":"Voici cinq habitudes pour une mode de vie sain que vous devriez envisager apr\u00e8s 50 ans. La forme physique n\u2019est pas si compliqu\u00e9e et la graisse n\u2019est pas le destin !","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/duoveo.com\/fr\/bien-etre-physique\/dossier-special\/cinq-astuces-pour-un-mode-de-vie-sain-et-perdre-du-poids-apres-50-ans\/#primaryimage","url":"https:\/\/duoveo.com\/wp-content\/uploads\/2020\/07\/1_K9BJOVXej6joCFAVSOVt4g.jpeg","contentUrl":"https:\/\/duoveo.com\/wp-content\/uploads\/2020\/07\/1_K9BJOVXej6joCFAVSOVt4g.jpeg","width":700,"height":466,"caption":"mode de vie sain"},{"@type":"WebSite","@id":"https:\/\/duoveo.com\/fr\/#website","url":"https:\/\/duoveo.com\/fr\/","name":"duoveo","description":"Your story, beautifully told - Created with WordPress managed by IONOS","publisher":{"@id":"https:\/\/duoveo.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/duoveo.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/duoveo.com\/fr\/#organization","name":"duoveo","url":"https:\/\/duoveo.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/duoveo.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/duoveo.com\/wp-content\/uploads\/2022\/03\/DuoVeo_logo-black_256.png","contentUrl":"https:\/\/duoveo.com\/wp-content\/uploads\/2022\/03\/DuoVeo_logo-black_256.png","width":256,"height":256,"caption":"duoveo"},"image":{"@id":"https:\/\/duoveo.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/duoveo","https:\/\/www.instagram.com\/duo.veo\/"]},{"@type":"Person","@id":"https:\/\/duoveo.com\/fr\/#\/schema\/person\/eb034ebdf6a49f948eeab02c6b1cce7f","name":"loic"}]}},"_links":{"self":[{"href":"https:\/\/duoveo.com\/fr\/wp-json\/wp\/v2\/posts\/20302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/duoveo.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/duoveo.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/duoveo.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/duoveo.com\/fr\/wp-json\/wp\/v2\/comments?post=20302"}],"version-history":[{"count":5,"href":"https:\/\/duoveo.com\/fr\/wp-json\/wp\/v2\/posts\/20302\/revisions"}],"predecessor-version":[{"id":20324,"href":"https:\/\/duoveo.com\/fr\/wp-json\/wp\/v2\/posts\/20302\/revisions\/20324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/duoveo.com\/fr\/wp-json\/wp\/v2\/media\/13177"}],"wp:attachment":[{"href":"https:\/\/duoveo.com\/fr\/wp-json\/wp\/v2\/media?parent=20302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/duoveo.com\/fr\/wp-json\/wp\/v2\/categories?post=20302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/duoveo.com\/fr\/wp-json\/wp\/v2\/tags?post=20302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}